{"id":2176,"date":"2024-11-08T03:01:30","date_gmt":"2024-11-08T02:01:30","guid":{"rendered":"https:\/\/www.libres-penseurs.net\/?p=2176"},"modified":"2025-01-18T02:43:44","modified_gmt":"2025-01-18T01:43:44","slug":"das-imperium-des-guten-und-seine-imaginaeren-kriege","status":"publish","type":"post","link":"https:\/\/www.libres-penseurs.net\/fr\/das-imperium-des-guten-und-seine-imaginaeren-kriege\/","title":{"rendered":"L&rsquo;Empire du Bien et ses guerres imaginaires"},"content":{"rendered":"<p><\/p>\n<h2>Ou comment miser sa chemise sur des illusions bellicistes<\/h2>\n<p><strong>par WILL SCHRYVER<\/strong><\/p>\n<p>Cela fait maintenant dix ans que j\u2019ai commenc\u00e9 \u00e0 r\u00e9fl\u00e9chir \u00e0 la n\u00e9cessit\u00e9 d\u2019investir prudemment pour pr\u00e9server et, je l\u2019esp\u00e8re, accro\u00eetre le modeste patrimoine que j\u2019avais accumul\u00e9 jusqu\u2019alors. J\u2019ai commenc\u00e9 par essayer d\u2019identifier les \u00ab&nbsp;experts&nbsp;\u00bb les plus avis\u00e9s et les plus perspicaces dans le domaine. Ce n\u2019\u00e9tait pas une mince affaire.<\/p>\n<p><!--more--><\/p>\n<p>Heureusement, au cours des dix ann\u00e9es qui ont pr\u00e9c\u00e9d\u00e9 ma prise de conscience de l\u2019importance des questions financi\u00e8res et macro\u00e9conomiques, fin 2014, j\u2019ai pass\u00e9 plusieurs ann\u00e9es \u00e0 d\u00e9couvrir que la plupart des universit\u00e9s occidentales sont une imposture domin\u00e9e par des ignorants hautement qualifi\u00e9s. J\u2019ai donc \u00e9t\u00e9 alert\u00e9 sur la probabilit\u00e9 que les soi-disant \u00ab experts \u00bb dans d\u2019autres domaines d\u2019\u00e9tudes soient tout aussi d\u00e9ficients intellectuellement, ind\u00e9pendamment de leur curriculum vitae apparemment impressionnant, du nombre de certificats encadr\u00e9s accroch\u00e9s \u00e0 leur mur et de l\u2019ampleur de leurs \u00ab&nbsp;actifs sous gestion&nbsp;\u00bb.<\/p>\n<p>Cela dit, il est devenu \u00e9vident au fil du temps que m\u00eame ceux que j\u2019avais initialement identifi\u00e9s comme des \u00ab experts \u00bb fiables pouvaient \u00eatre bien inform\u00e9s la plupart du temps, et pourtant \u00eatre sujets \u00e0 des angles morts qui les rendaient vuln\u00e9rables \u00e0 des erreurs fatales pouvant souvent annuler leur jugement apparemment correct sur tout le reste.<\/p>\n<p>Dans le contexte des questions financi\u00e8res, il faut comprendre que l\u2019\u00ab&nbsp;assouplissement quantitatif&nbsp;\u00bb et les taux d\u2019int\u00e9r\u00eat proches de z\u00e9ro qui ont suivi la soi-disant \u00ab&nbsp;Grande crise financi\u00e8re&nbsp;\u00bb de 2007 \u00e0 2009 ont \u00e9t\u00e9 une mar\u00e9e qui a port\u00e9 un grand nombre de bateaux dirig\u00e9s par des imb\u00e9ciles dont la folie ne serait reconnue que plusieurs ann\u00e9es plus tard, lorsque les cons\u00e9quences de la prodigalit\u00e9 des banques centrales seraient r\u00e9v\u00e9l\u00e9es.<\/p>\n<p>Pourtant, la plupart des \u00ab&nbsp;gourous&nbsp;\u00bb de l\u2019investissement dont j\u2019avais appris \u00e0 respecter l\u2019analyse ont r\u00e9ussi \u00e0 traverser avec succ\u00e8s l\u2019ouragan de l\u2019inflation des prix qui a d\u00e9ferl\u00e9 sur la plan\u00e8te \u00e0 la suite de l\u2019hyst\u00e9rie li\u00e9e au Covid \u2013 une temp\u00eate qui a ensuite \u00e9t\u00e9 suivie par la hausse des taux d\u2019int\u00e9r\u00eat de la R\u00e9serve f\u00e9d\u00e9rale dans une tentative fr\u00e9n\u00e9tique d\u2019endiguer la mar\u00e9e inflationniste.<\/p>\n<p>Puis la Troisi\u00e8me Guerre mondiale a commenc\u00e9.<\/p>\n<p>Bien s\u00fbr, m\u00eame \u00e0 ce stade, pr\u00e8s de trois ans apr\u00e8s le d\u00e9but de cette guerre, peu de gens reconnaissent ce qu\u2019elle est r\u00e9ellement. Encore moins nombreux sont ceux qui reconnaissent \u00e0 quel point les param\u00e8tres g\u00e9opolitiques et militaires de la guerre elle-m\u00eame ont \u00e9t\u00e9 radicalement modifi\u00e9s par rapport \u00e0 ce qu\u2019ils \u00e9taient pendant \u00ab&nbsp;l\u2019interr\u00e8gne unipolaire am\u00e9ricain&nbsp;\u00bb qui a d\u00e9but\u00e9 avec la dissolution de l\u2019Union sovi\u00e9tique.<\/p>\n<p>En effet, l\u2019immense majorit\u00e9 des Am\u00e9ricains estime que le \u00ab&nbsp;moment unipolaire&nbsp;\u00bb se poursuit pour l\u2019essentiel intact et sans menace. Dans les environnements tr\u00e8s isol\u00e9s de Wall Street et de la Silicon Valley, la foi dans la supr\u00e9matie \u00e9crasante des hautes technologies et des prouesses militaires am\u00e9ricaines reste presque enti\u00e8rement in\u00e9branlable, malgr\u00e9 les indications toujours plus nombreuses du contraire \u2013 des choses sur lesquelles j\u2019\u00e9cris depuis plusieurs ann\u00e9es maintenant.<\/p>\n<p>La plupart des dieux de la haute technologie et de la finance am\u00e9ricaines, et ceux qui les v\u00e9n\u00e8rent, ne peuvent tout simplement pas discerner \u00e0 quel point la puissance am\u00e9ricaine sous toutes ses formes s\u2019est progressivement \u00e9rod\u00e9e au cours du XXIe si\u00e8cle , et que cette \u00e9rosion s\u2019est acc\u00e9l\u00e9r\u00e9e de fa\u00e7on spectaculaire ces derni\u00e8res ann\u00e9es.<\/p>\n<p>Pour la plupart des \u00e9lites occidentales et de leurs acolytes, nous sommes encore au d\u00e9but de l\u2019ann\u00e9e 1991, et Norman Schwarzkopf dirige une arm\u00e9e d\u2019un million d\u2019hommes contre les malheureux Irakiens dans une d\u00e9monstration de puissance militaire qui effacerait enfin l\u2019am\u00e8re humiliation du Vietnam de la psych\u00e9 am\u00e9ricaine.<\/p>\n<p>Ces gens ont adh\u00e9r\u00e9 religieusement aux fantasmes hollywoodiens de la domination inattaquable de la superpuissance am\u00e9ricaine. Et \u00e9tant donn\u00e9 que l\u2019Ukraine et Isra\u00ebl sont consid\u00e9r\u00e9s comme de simples appendices de cette suppos\u00e9e supr\u00e9matie militaire am\u00e9ricaine, les th\u00e9\u00e2tres de la Troisi\u00e8me Guerre mondiale en Europe de l\u2019Est et au Levant ont donn\u00e9 lieu \u00e0 des exemples extr\u00eames d\u2019un tsunami de propagande sans pr\u00e9c\u00e9dent que j\u2019ai coutume d\u2019appeler \u00ab&nbsp;la guerre imaginaire&nbsp;\u00bb.<\/p>\n<p>Cette expression que j\u2019ai invent\u00e9e au d\u00e9but de la guerre en Ukraine trouve son origine dans une d\u00e9claration qu\u2019aurait prononc\u00e9e un g\u00e9n\u00e9ral isra\u00e9lien anonyme au lendemain de la guerre de 2006 au Sud-Liban \u2013 une guerre dont l\u2019issue finale fut une d\u00e9faite strat\u00e9gique d\u00e9cisive pour Isra\u00ebl, mais que les Isra\u00e9liens ont ensuite tent\u00e9 de transformer en une grande victoire. C\u2019est dans ce contexte que le g\u00e9n\u00e9ral isra\u00e9lien aurait d\u00e9clar\u00e9&nbsp;: \u00ab&nbsp;Si vous ne pouvez pas gagner une vraie guerre, gagnez-en une imaginaire.&nbsp;\u00bb<\/p>\n<p>C\u2019est pr\u00e9cis\u00e9ment l\u2019approche narrative que nous avons observ\u00e9e en Ukraine au cours des deux derni\u00e8res ann\u00e9es.<\/p>\n<p>La plupart des Am\u00e9ricains, et la plupart des gens dans le monde qui croient aux r\u00e9cits occidentaux dominants, sont convaincus que les Russes ont subi une d\u00e9faite strat\u00e9gique \u00e9crasante en Ukraine&nbsp;; que l\u2019arm\u00e9e russe s\u2019est r\u00e9v\u00e9l\u00e9e \u00eatre une foule ivre et mal entra\u00een\u00e9e&nbsp;; que la doctrine militaire russe est imb\u00e9cile ; que l\u2019\u00e9quipement russe est de la camelote&nbsp;; que la technologie militaire russe a des d\u00e9cennies de retard sur ses homologues occidentales ; que les jouets de guerre am\u00e9ricains et autres de l\u2019OTAN envoy\u00e9s en Ukraine ont domin\u00e9 le champ de bataille, etc., etc.<\/p>\n<p>On croit les m\u00eames choses \u00e0 propos de la Chine, de sa culture et de ses capacit\u00e9s militaires.<\/p>\n<p>Et, bien s\u00fbr, les Iraniens et les Nord-Cor\u00e9ens sont l\u2019objet d\u2019une d\u00e9rision encore plus grande.<\/p>\n<p>Juste aujourd&rsquo;hui, j&rsquo;ai lu un court article d&rsquo;un CIO de fonds sp\u00e9culatifs de Wall Street assez connu, dans lequel il a \u00e9crit le paragraphe suivant, compl\u00e8tement fictif (et pourtant largement admis)&nbsp;:<\/p>\n<p>\u00ab&nbsp;Isra\u00ebl a envoy\u00e9 100 avions pour un vol de 2000 km pour attaquer T\u00e9h\u00e9ran. Aucun n&rsquo;a \u00e9t\u00e9 abattu. D&rsquo;abord, l&rsquo;arm\u00e9e isra\u00e9lienne a d\u00e9truit les d\u00e9fenses a\u00e9riennes de l&rsquo;Iran. Ces syst\u00e8mes antia\u00e9riens russes S-300 peuvent maintenant \u00eatre retrouv\u00e9s d\u00e9mont\u00e9s dans de grands crat\u00e8res \u00e0 travers la r\u00e9gion (le nouveau syst\u00e8me russe S-400 n&rsquo;a pas r\u00e9pondu aux attentes en Ukraine et le S-500 est en phase de test). Les d\u00e9fenses a\u00e9riennes iraniennes \u00e9tant hors service, les avions isra\u00e9liens ont pu s&rsquo;en prendre \u00e0 toutes les cibles qu&rsquo;ils voulaient \u00e0 T\u00e9h\u00e9ran. Cette fois, ils ont \u00e9vit\u00e9 les mollahs. La prochaine fois, qui sait&nbsp;? Telle est la nature de la guerre pour ceux qui ont une technologie sup\u00e9rieure.&nbsp;\u00bb<\/p>\n<p>Peu importe que litt\u00e9ralement <strong>toutes<\/strong> ses affirmations soient manifestement fausses : ce pr\u00e9tendu titan de la finance am\u00e9ricaine a l\u2019intention de miser toute sa fortune sur les hypoth\u00e8ses fallacieuses des guerres imaginaires dont il s\u2019est convaincu lui-m\u00eame qu\u2019elles ont r\u00e9ellement lieu.<\/p>\n<p>Bien entendu, les deux principaux candidats \u00e0 la pr\u00e9sidence, la quasi-totalit\u00e9 du Congr\u00e8s am\u00e9ricain et une grande partie de l\u2019immense mar\u00e9cage de la bureaucratie gouvernementale am\u00e9ricaine \u00e0 Washington sont \u00e9galement convaincus de l\u2019indomptabilit\u00e9 de la puissance militaire imp\u00e9riale am\u00e9ricaine, et ils sont impatients de donner \u00e0 l\u2019actuel \u00ab&nbsp;axe du mal&nbsp;\u00bb \u00e0 Moscou, P\u00e9kin et T\u00e9h\u00e9ran une le\u00e7on qu\u2019ils n\u2019oublieront pas de sit\u00f4t.<\/p>\n<p>En fin de compte \u2013 et cela viendra plus t\u00f4t que pr\u00e9vu \u2013 la seule chose qui ne sera pas vite oubli\u00e9e est la bri\u00e8vet\u00e9 du moment unipolaire am\u00e9ricain, et la fa\u00e7on choquante et soudaine avec laquelle tout s\u2019est effondr\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en Deutsch. Oder: wie man sein letztes Hemd f\u00fcr Kriegsillusionen hergibt von Will Schryver Es ist jetzt zehn Jahre her, dass ich anfing, \u00fcber die Notwendigkeit vorsichtiger Investitionen nachzudenken, um das bescheidene Verm\u00f6gen, das ich bis dahin angesammelt hatte, zu erhalten und hoffentlich zu vermehren. Zun\u00e4chst versuchte ich, die&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1],"tags":[],"class_list":["post-2176","post","type-post","status-publish","format-standard","hentry","category-aktuelles","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/2176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/comments?post=2176"}],"version-history":[{"count":10,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/2176\/revisions"}],"predecessor-version":[{"id":2193,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/2176\/revisions\/2193"}],"wp:attachment":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/media?parent=2176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/categories?post=2176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/tags?post=2176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}