{"id":590,"date":"2016-01-31T18:15:00","date_gmt":"2016-01-31T17:15:00","guid":{"rendered":"http:\/\/www.freidenker.org\/wuf\/cms\/?p=590"},"modified":"2024-02-15T14:18:35","modified_gmt":"2024-02-15T13:18:35","slug":"liberte-de-conscience-et-liberte-dexpression","status":"publish","type":"post","link":"https:\/\/www.libres-penseurs.net\/fr\/liberte-de-conscience-et-liberte-dexpression\/","title":{"rendered":"Paris 12 F\u00e9vrier 2016: Libert\u00e9 de conscience et Libert\u00e9 d&rsquo;expression"},"content":{"rendered":"<p><a href=\"\/wp-wuf\/wp-content\/uploads\/2016\/01\/flyer2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-591\" title=\"flyer2-2016-02-12\" src=\"\/wp-wuf\/wp-content\/uploads\/2016\/01\/flyer2-209x300.jpg\" alt=\"flyer2-2016-02-12\" width=\"209\" height=\"300\" \/><\/a><\/p>\n<p>Chers Camarades,<\/p>\n<p>le Bureau et le Conseil International de l&rsquo;UMPL se r\u00e9uniront le<\/p>\n<p>Vendredi 12 F\u00e9vrier 2016 de 10 \u00e0 17 heures \u00e0 la<br \/>\nMairie du 10\u00e8 Arrondissement de Paris.<br \/>\n72, rue du Fbg St Martin<br \/>\n(M\u00e9tro Ch\u00e2teau d&rsquo;Eau Ligne 4)<\/p>\n<p>10 &#8211; 12\u00a0:30 heures: R\u00e9union commune du Bureau et du Conseil International<\/p>\n<p><!--more-->\u00a0ORDRE DU JOUR<br \/>\n&#8211; Compte-Rendu de la R\u00e9union du Bureaux et du Conseil International `<br \/>\n\u00e0 Spa le 19 septembre 2014<br \/>\n&#8211; Le point sur la tr\u00e9sorerie<br \/>\n&#8211; Activit\u00e9s des associations<br \/>\n&#8211; Si\u00e8ge social de l&rsquo;UMLP<br \/>\n&#8211; Pr\u00e9sentation et vote sur les motions et r\u00e9solutions<br \/>\n&#8211; \u00c9lection de nouveaux membres du bureau<br \/>\n&#8211; Date et lieu de la prochaine r\u00e9union<\/p>\n<p>12\u00a0:30 &#8211; 13\u00a0:45 heures Repas pris en commun au restaurant<br \/>\nLe Saulnier 39 Bd de Strasbourg, Passage Reihlac ( \u00e0 180m de la mairie)<\/p>\n<p>13\u00a0:45 &#8211; 17 heures COLLOQUE<br \/>\nOrganis\u00e9 par l&rsquo;Association des Libres Penseurs de France<br \/>\nLibert\u00e9 de Conscience et Libert\u00e9 d&rsquo;Expression<br \/>\navec:<br \/>\nCharles Arrambourou, juriste (magistrat financier honoraire)<br \/>\nKlaus Hartmann, pr\u00e9sident de l&rsquo;UMLP<br \/>\nG\u00e9rard Delfau, pr\u00e9sident d&rsquo;EGALE ( Egalit\u00e9, la\u00efcit\u00e9, Europe)<\/p>\n<p>INDICATIONS PRATIQUES<\/p>\n<p>&#8211; Pour ceux qui seront d\u00e9j\u00e0 sur place le Jeudi 11 F\u00e9vrier 2016 notre camarade Gilles Poulet a pr\u00e9vu la possibilit\u00e9 de se retrouver d\u00e9j\u00e0 le soir pour prendre le diner. Il a besoin de savoir combien nous serions, et demande de lui indiquer par retour sur son adresse courriel (g.jl.Poulet@orange.fr), qui veut partager ce repas. Il prendra alors les dispositions ad hoc pour nous assurer une table au restaurant l&rsquo;Aveyronnais, 120, rue du Fbg St Martin.<\/p>\n<p>&#8211; Chaque responsable de groupe doit informer ses camarades d\u00e9sirant assister au CI<\/p>\n<p>Bien amicalement<\/p>","protected":false},"excerpt":{"rendered":"<p>Chers Camarades, le Bureau et le Conseil International de l&rsquo;UMPL se r\u00e9uniront le Vendredi 12 F\u00e9vrier 2016 de 10 \u00e0 17 heures \u00e0 la Mairie du 10\u00e8 Arrondissement de Paris. 72, rue du Fbg St Martin (M\u00e9tro Ch\u00e2teau d&rsquo;Eau Ligne 4) 10 &#8211; 12\u00a0:30 heures: R\u00e9union commune du Bureau et du Conseil International<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-590","post","type-post","status-publish","format-standard","hentry","category-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":3,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":716,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/posts\/590\/revisions\/716"}],"wp:attachment":[{"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.libres-penseurs.net\/fr\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}